{"id":712,"count":1,"description":"","link":"https:\/\/queens.name\/en\/tag\/queens-dairies","name":"queens dairies","slug":"queens-dairies","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/queens.name\/en\/wp-json\/wp\/v2\/tags\/712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queens.name\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/queens.name\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/queens.name\/en\/wp-json\/wp\/v2\/posts?tags=712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}