{"id":1158,"count":1,"description":"","link":"https:\/\/queens.name\/ru\/tag\/oklendskoe-ozero","name":"\u041e\u043a\u043b\u0435\u043d\u0434\u0441\u043a\u043e\u0435 \u043e\u0437\u0435\u0440\u043e","slug":"oklendskoe-ozero","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/queens.name\/ru\/wp-json\/wp\/v2\/tags\/1158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queens.name\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/queens.name\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/queens.name\/ru\/wp-json\/wp\/v2\/posts?tags=1158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}