{"id":1164,"count":1,"description":"","link":"https:\/\/queens.name\/uk\/tag\/ozero-kissena","name":"\u043e\u0437\u0435\u0440\u043e \u041a\u0456\u0441\u0441\u0435\u043d\u0430","slug":"ozero-kissena","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/tags\/1164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/posts?tags=1164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}