{"id":1465,"count":1,"description":"","link":"https:\/\/queens.name\/uk\/t-the-glasshouse","name":"The GlassHouse","slug":"the-glasshouse","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/tags\/1465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/posts?tags=1465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}