{"id":559,"count":1,"description":"","link":"https:\/\/queens.name\/uk\/tag\/queens-county","name":"Queens County","slug":"queens-county","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/tags\/559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/queens.name\/uk\/wp-json\/wp\/v2\/posts?tags=559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}